{"id":311,"date":"2017-06-09T09:41:38","date_gmt":"2017-06-09T07:41:38","guid":{"rendered":"https:\/\/www.schuh-germann.de\/blog\/?p=311"},"modified":"2017-06-09T09:50:15","modified_gmt":"2017-06-09T07:50:15","slug":"wanderschuhe-damen-herren-kinder","status":"publish","type":"post","link":"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/","title":{"rendered":"F\u00fcr einen guten Lauf: Wanderschuhe f\u00fcr die ganze Familie"},"content":{"rendered":"<p>Thema Wanderschuhe: Wen es im Sommerurlaub nicht ans Meer zieht, der steuert die Berge an, in denen es sich in den Sommermonaten wunderbar wandern l\u00e4sst. Mit dem richtigen Schuhwerk k\u00f6nnen Sie Spazierg\u00e4nge bei jedem Wetter machen, Trekkingtouren mit gesunden F\u00fc\u00dfen planen und auch steile Wanderpfade erklimmen. Wir stellen Ihnen stellvertretend f\u00fcr unser breites Sortiment an Wanderschuhen unsere drei beliebtesten Marken vor.<br \/>\n<!--more--><\/p>\n<h2>Etwas f\u00fcr\u2019s Auge: Die bunten Wanderschuhe von Salomon<\/h2>\n<p>In knalligem Rosa, erfrischendem Blau oder knalligem Gr\u00fcn: Die <a href=\"https:\/\/www.schuh-germann.de\/marken\/salomon\/\">Wanderschuhe von Salomon<\/a> erstrahlen in den sch\u00f6nsten Farben und sind so ein Highlight f\u00fcr jedes Wanderoutfit. Neben dem Design \u00fcberzeugen das hervorragende Material und die Details des Wanderschuhs, in jedem Modell stecken mehrere Jahrzehnte Erfahrung und Expertise. Der Franzose Francois Salomon gr\u00fcndete sein Unternehmen 1947. Zun\u00e4chst wurden von Salomon Skibretter hergestellt, sp\u00e4ter kamen alpine Sportschuhe dazu. Diese wurden mit viel Herzblut gefertigt, denn der Gr\u00fcnder war selbst begeisterter Alpinsportler und kannte so die Herausforderungen und Anspr\u00fcche an einen guten und langlebigen Wanderschuh. Die Salomon Sportschuhe gibt es f\u00fcr Damen, Herren und Kinder.<\/p>\n<p>&nbsp;<\/p>\n<h2>F\u00fcr anspruchsvolle Touren: Die Wanderschuhe von Lowa<\/h2>\n<p>F\u00fcr eine mehrt\u00e4gige Trekkingtour durch alpines Gel\u00e4nde werden andere Wanderschuhe ben\u00f6tigt als f\u00fcr den Ausflug in die Berge mit der ganzen Familie. F\u00fcr Alpinsportler und Abenteuer haben sich die <a href=\"https:\/\/www.schuh-germann.de\/marken\/lowa\/\">Trekkingschuhe von Lowa<\/a> bew\u00e4hrt. Lorenz Wagner gr\u00fcndete sein Unternehmem im Jahr 1923 in Bayern \u2013 noch heute werden die vielf\u00e4ltigen Modelle in Deutschland und Europa gefertigt. F\u00fcr spezielle Anspr\u00fcche werden Wanderschuhe in den Sparten Alpin, Backpacking, Trekking, All Terrain Collection, Speedhiking, Travel, Cold Weather Boots und Kids angeboten. Jedes Modell passt sich exakt an die klimatischen und wetterbedingten Anspr\u00fcche, die jeweiligen Untergr\u00fcnde sowie die Sportart bzw. Freizeitaktivit\u00e4t an. Unter allen Trekkingschuhen sind Schuhe von Lowa die Spezialisten.<\/p>\n<p>&nbsp;<\/p>\n<h2>300 Jahre zwiegen\u00e4ht \u2013 Wanderschuhe von Meindl<\/h2>\n<p>Im bayrischen Kirchansch\u00f6ring trifft Handwerk auf Technologie: Vor mehr als 300 Jahren stellte der Schuhmacher Petrus Meindl handwerkliche Meisterwerke her \u2013 genauso wie das daraus resultierende Unternehmen es heute noch tut. Die <a href=\"https:\/\/www.schuh-germann.de\/marken\/meindl\/\">Wanderschuhe von Meindl<\/a> geh\u00f6ren zu den Marktf\u00fchrern im Bereich Outdoorschuhe. In unserem Sortiment finden Sie Damen-Wanderschuhe, Herren-Wanderschuhe sowie in der Junior-Linie Meindl-Schuhe f\u00fcr Kinder. Die verschiedenen Modelle zeichnen sich durch eine hervorragende Verarbeitung aus. So k\u00f6nnen die F\u00fc\u00dfe durch die besondere MFS- und MFS-Vakuum-Qualit\u00e4t auch bei l\u00e4ngeren Wanderungen gut atmen. Zudem sind die Trekkingschuhe zwiegen\u00e4ht, wodurch sie besonders robust sind und bei vielen Ausfl\u00fcgen und Wanderungen treue Begleiter sind.<\/p>\n<p>Planen Sie Ihren Wanderurlaub 2017? Dann finden Sie f\u00fcr sich und Ihre Familie den passenden <a href=\"https:\/\/www.schuh-germann.de\/outdoor\/\">Wanderschuh<\/a>, der Sie sicher und bequem ans Ziel bringt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Thema Wanderschuhe: Wen es im Sommerurlaub nicht ans Meer zieht, der steuert die Berge an, in denen es sich in den Sommermonaten wunderbar wandern l\u00e4sst. Mit dem richtigen Schuhwerk k\u00f6nnen Sie Spazierg\u00e4nge bei jedem Wetter machen, Trekkingtouren mit gesunden F\u00fc\u00dfen planen und auch steile Wanderpfade erklimmen. Wir stellen Ihnen stellvertretend f\u00fcr unser breites Sortiment an [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":321,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,2,225],"tags":[370,368,369,367],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v16.1 (Yoast SEO v16.8) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u00fcr einen guten Lauf: Wanderschuhe f\u00fcr die ganze Familie - Fashion &amp; Lifestyle\" \/>\n<meta property=\"og:description\" content=\"Thema Wanderschuhe: Wen es im Sommerurlaub nicht ans Meer zieht, der steuert die Berge an, in denen es sich in den Sommermonaten wunderbar wandern l\u00e4sst. Mit dem richtigen Schuhwerk k\u00f6nnen Sie Spazierg\u00e4nge bei jedem Wetter machen, Trekkingtouren mit gesunden F\u00fc\u00dfen planen und auch steile Wanderpfade erklimmen. Wir stellen Ihnen stellvertretend f\u00fcr unser breites Sortiment an [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/\" \/>\n<meta property=\"og:site_name\" content=\"Fashion &amp; Lifestyle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schuh.germann\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-09T07:41:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-06-09T07:50:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.schuh-germann.de\/blog\/wp-content\/uploads\/2017\/06\/wanderschuhe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1900\" \/>\n\t<meta property=\"og:image:height\" content=\"1267\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Schuh Germann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\/\/www.schuh-germann.de\/blog\/#organization\",\"name\":\"Schuh Germann GmbH\",\"url\":\"https:\/\/www.schuh-germann.de\/blog\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/schuh.germann\/\",\"https:\/\/www.instagram.com\/schuhgermann\/\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.schuh-germann.de\/blog\/#logo\",\"inLanguage\":\"de-DE\",\"url\":\"https:\/\/www.schuh-germann.de\/blog\/wp-content\/uploads\/2017\/03\/germann_logo_rot.png\",\"contentUrl\":\"https:\/\/www.schuh-germann.de\/blog\/wp-content\/uploads\/2017\/03\/germann_logo_rot.png\",\"width\":460,\"height\":189,\"caption\":\"Schuh Germann GmbH\"},\"image\":{\"@id\":\"https:\/\/www.schuh-germann.de\/blog\/#logo\"},\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/#webpage\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.schuh-germann.de\/blog\/#website\",\"url\":\"https:\/\/www.schuh-germann.de\/blog\/\",\"name\":\"Fashion &amp; Lifestyle\",\"description\":\"SHOE ! STYLES\",\"publisher\":{\"@id\":\"https:\/\/www.schuh-germann.de\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.schuh-germann.de\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/#primaryimage\",\"inLanguage\":\"de-DE\",\"url\":\"https:\/\/www.schuh-germann.de\/blog\/wp-content\/uploads\/2017\/06\/wanderschuhe.jpg\",\"contentUrl\":\"https:\/\/www.schuh-germann.de\/blog\/wp-content\/uploads\/2017\/06\/wanderschuhe.jpg\",\"width\":1900,\"height\":1267,\"caption\":\"Wanderschuhe kaufen - Depositphotos lzf\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/#webpage\",\"url\":\"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/\",\"name\":\"F\\u00fcr einen guten Lauf: Wanderschuhe f\\u00fcr die ganze Familie - Fashion &amp; Lifestyle\",\"isPartOf\":{\"@id\":\"https:\/\/www.schuh-germann.de\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/#primaryimage\"},\"datePublished\":\"2017-06-09T07:41:38+00:00\",\"dateModified\":\"2017-06-09T07:50:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.schuh-germann.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F\\u00fcr einen guten Lauf: Wanderschuhe f\\u00fcr die ganze Familie\"}]},{\"@type\":[\"Article\",\"NewsArticle\"],\"@id\":\"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.schuh-germann.de\/blog\/#\/schema\/person\/2c78ced8e35f47c19279a3a2f98da03b\"},\"headline\":\"F\\u00fcr einen guten Lauf: Wanderschuhe f\\u00fcr die ganze Familie\",\"datePublished\":\"2017-06-09T07:41:38+00:00\",\"dateModified\":\"2017-06-09T07:50:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/#webpage\"},\"wordCount\":463,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.schuh-germann.de\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.schuh-germann.de\/blog\/wp-content\/uploads\/2017\/06\/wanderschuhe.jpg\",\"keywords\":[\"Lowa\",\"Meindl\",\"Salomon\",\"Wanderschuhe\"],\"articleSection\":{\"1\":\"Featured\",\"2\":\"Produkte\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/#respond\"]}],\"copyrightYear\":\"2017\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.schuh-germann.de\/blog\/#organization\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.schuh-germann.de\/blog\/#\/schema\/person\/2c78ced8e35f47c19279a3a2f98da03b\",\"name\":\"Schuh Germann\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.schuh-germann.de\/blog\/#personlogo\",\"inLanguage\":\"de-DE\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d76d226f119bb70e9f5333d1910df36f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d76d226f119bb70e9f5333d1910df36f?s=96&d=mm&r=g\",\"caption\":\"Schuh Germann\"},\"sameAs\":[\"https:\/\/www.schuh-germann.de\/\"],\"url\":\"https:\/\/www.schuh-germann.de\/blog\/author\/schuh-germann\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/","og_locale":"de_DE","og_type":"article","og_title":"F\u00fcr einen guten Lauf: Wanderschuhe f\u00fcr die ganze Familie - Fashion &amp; Lifestyle","og_description":"Thema Wanderschuhe: Wen es im Sommerurlaub nicht ans Meer zieht, der steuert die Berge an, in denen es sich in den Sommermonaten wunderbar wandern l\u00e4sst. Mit dem richtigen Schuhwerk k\u00f6nnen Sie Spazierg\u00e4nge bei jedem Wetter machen, Trekkingtouren mit gesunden F\u00fc\u00dfen planen und auch steile Wanderpfade erklimmen. Wir stellen Ihnen stellvertretend f\u00fcr unser breites Sortiment an [&hellip;]","og_url":"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/","og_site_name":"Fashion &amp; Lifestyle","article_publisher":"https:\/\/www.facebook.com\/schuh.germann\/","article_published_time":"2017-06-09T07:41:38+00:00","article_modified_time":"2017-06-09T07:50:15+00:00","og_image":[{"width":1900,"height":1267,"url":"https:\/\/www.schuh-germann.de\/blog\/wp-content\/uploads\/2017\/06\/wanderschuhe.jpg","path":"\/var\/www\/html\/blog\/wp-content\/uploads\/2017\/06\/wanderschuhe.jpg","size":"full","id":"321","alt":"Wanderschuhe kaufen - Depositphotos lzf","pixels":2407300,"type":"image\/jpeg"}],"twitter_card":"summary","twitter_misc":{"Verfasst von":"Schuh Germann","Gesch\u00e4tzte Lesezeit":"2 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Organization","Place"],"@id":"https:\/\/www.schuh-germann.de\/blog\/#organization","name":"Schuh Germann GmbH","url":"https:\/\/www.schuh-germann.de\/blog\/","sameAs":["https:\/\/www.facebook.com\/schuh.germann\/","https:\/\/www.instagram.com\/schuhgermann\/"],"logo":{"@type":"ImageObject","@id":"https:\/\/www.schuh-germann.de\/blog\/#logo","inLanguage":"de-DE","url":"https:\/\/www.schuh-germann.de\/blog\/wp-content\/uploads\/2017\/03\/germann_logo_rot.png","contentUrl":"https:\/\/www.schuh-germann.de\/blog\/wp-content\/uploads\/2017\/03\/germann_logo_rot.png","width":460,"height":189,"caption":"Schuh Germann GmbH"},"image":{"@id":"https:\/\/www.schuh-germann.de\/blog\/#logo"},"mainEntityOfPage":{"@id":"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/#webpage"}},{"@type":"WebSite","@id":"https:\/\/www.schuh-germann.de\/blog\/#website","url":"https:\/\/www.schuh-germann.de\/blog\/","name":"Fashion &amp; Lifestyle","description":"SHOE ! STYLES","publisher":{"@id":"https:\/\/www.schuh-germann.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.schuh-germann.de\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":"ImageObject","@id":"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/#primaryimage","inLanguage":"de-DE","url":"https:\/\/www.schuh-germann.de\/blog\/wp-content\/uploads\/2017\/06\/wanderschuhe.jpg","contentUrl":"https:\/\/www.schuh-germann.de\/blog\/wp-content\/uploads\/2017\/06\/wanderschuhe.jpg","width":1900,"height":1267,"caption":"Wanderschuhe kaufen - Depositphotos lzf"},{"@type":"WebPage","@id":"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/#webpage","url":"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/","name":"F\u00fcr einen guten Lauf: Wanderschuhe f\u00fcr die ganze Familie - Fashion &amp; Lifestyle","isPartOf":{"@id":"https:\/\/www.schuh-germann.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/#primaryimage"},"datePublished":"2017-06-09T07:41:38+00:00","dateModified":"2017-06-09T07:50:15+00:00","breadcrumb":{"@id":"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.schuh-germann.de\/blog\/"},{"@type":"ListItem","position":2,"name":"F\u00fcr einen guten Lauf: Wanderschuhe f\u00fcr die ganze Familie"}]},{"@type":["Article","NewsArticle"],"@id":"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/#article","isPartOf":{"@id":"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/#webpage"},"author":{"@id":"https:\/\/www.schuh-germann.de\/blog\/#\/schema\/person\/2c78ced8e35f47c19279a3a2f98da03b"},"headline":"F\u00fcr einen guten Lauf: Wanderschuhe f\u00fcr die ganze Familie","datePublished":"2017-06-09T07:41:38+00:00","dateModified":"2017-06-09T07:50:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/#webpage"},"wordCount":463,"commentCount":0,"publisher":{"@id":"https:\/\/www.schuh-germann.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/#primaryimage"},"thumbnailUrl":"https:\/\/www.schuh-germann.de\/blog\/wp-content\/uploads\/2017\/06\/wanderschuhe.jpg","keywords":["Lowa","Meindl","Salomon","Wanderschuhe"],"articleSection":{"1":"Featured","2":"Produkte"},"inLanguage":"de-DE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.schuh-germann.de\/blog\/wanderschuhe-damen-herren-kinder\/#respond"]}],"copyrightYear":"2017","copyrightHolder":{"@id":"https:\/\/www.schuh-germann.de\/blog\/#organization"}},{"@type":"Person","@id":"https:\/\/www.schuh-germann.de\/blog\/#\/schema\/person\/2c78ced8e35f47c19279a3a2f98da03b","name":"Schuh Germann","image":{"@type":"ImageObject","@id":"https:\/\/www.schuh-germann.de\/blog\/#personlogo","inLanguage":"de-DE","url":"https:\/\/secure.gravatar.com\/avatar\/d76d226f119bb70e9f5333d1910df36f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d76d226f119bb70e9f5333d1910df36f?s=96&d=mm&r=g","caption":"Schuh Germann"},"sameAs":["https:\/\/www.schuh-germann.de\/"],"url":"https:\/\/www.schuh-germann.de\/blog\/author\/schuh-germann\/"}]}},"_links":{"self":[{"href":"https:\/\/www.schuh-germann.de\/blog\/wp-json\/wp\/v2\/posts\/311"}],"collection":[{"href":"https:\/\/www.schuh-germann.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schuh-germann.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schuh-germann.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schuh-germann.de\/blog\/wp-json\/wp\/v2\/comments?post=311"}],"version-history":[{"count":6,"href":"https:\/\/www.schuh-germann.de\/blog\/wp-json\/wp\/v2\/posts\/311\/revisions"}],"predecessor-version":[{"id":320,"href":"https:\/\/www.schuh-germann.de\/blog\/wp-json\/wp\/v2\/posts\/311\/revisions\/320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schuh-germann.de\/blog\/wp-json\/wp\/v2\/media\/321"}],"wp:attachment":[{"href":"https:\/\/www.schuh-germann.de\/blog\/wp-json\/wp\/v2\/media?parent=311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schuh-germann.de\/blog\/wp-json\/wp\/v2\/categories?post=311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schuh-germann.de\/blog\/wp-json\/wp\/v2\/tags?post=311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}